{"id":32030,"date":"2024-02-16T02:29:15","date_gmt":"2024-02-16T01:29:15","guid":{"rendered":"http:\/\/vinness.it\/?post_type=product&#038;p=32030"},"modified":"2026-04-25T23:30:51","modified_gmt":"2026-04-25T21:30:51","slug":"nero-davola-riserva-don-antonio-2018-morgante","status":"publish","type":"product","link":"https:\/\/www.vinness.it\/zh\/catalogo\/vineria\/vini-vineria\/rosso\/nero-davola-riserva-don-antonio-2018-morgante\/","title":{"rendered":"Nero d&#8217;Avola Riserva &#8220;Don Antonio&#8221; 2018 &#8211; Morgante"},"content":{"rendered":"<div data-elementor-type=\"product-post\" data-elementor-id=\"32030\" class=\"elementor elementor-32030\" data-elementor-post-type=\"product\">\n\t\t\t\t<div class=\"elementor-element elementor-element-16e0439d e-con-full e-flex e-con e-parent\" data-id=\"16e0439d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7eb50a31 e-flex e-con-boxed e-con e-child\" data-id=\"7eb50a31\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79d4a05f elementor-widget elementor-widget-heading\" data-id=\"79d4a05f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nero d\u2019Avola Riserva\n<br>\n\u201cDon Antonio\u201d Morgante<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-686d23f8 e-flex e-con-boxed e-con e-child\" data-id=\"686d23f8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-186d2579 elementor-widget elementor-widget-gallery\" data-id=\"186d2579\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;masonry&quot;,&quot;columns&quot;:2,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:24,&quot;sizes&quot;:[]},&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-2c6fe91a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c6fe91a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-456c8d29\" data-id=\"456c8d29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1164b29a elementor-widget elementor-widget-heading\" data-id=\"1164b29a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Il Nero d\u2019Avola Riserva \u2018Don Antonio\u2019 rappresenta l\u2019etichetta di punta della cantina siciliana Morgante, un vino rosso che esalta la speziatura e l\u2019intensit\u00e0 caratteristiche del Nero d\u2019Avola, variet\u00e0 a bacca nera pi\u00f9 diffusa dell\u2019isola. Questa bottiglia venne prodotta per la prima volta con la vendemmia 1998, distinguendosi fin da subito per pregio e qualit\u00e0 e configurandosi come la risposta della famiglia Morgante ai cambiamenti del gusto dei consumatori che erano in atto, pi\u00f9 orientati verso vini che raccontassero il territorio. Venti anni pi\u00f9 tardi, nel 2018, il \u2018Don Antonio\u2019 si \u00e8 arricchito della dicitura \u201cRiserva\u201d, a evidenziare ancor di pi\u00f9 il suo prestigio con un termine comprensibile anche a livello internazionale.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ae96b35 elementor-widget elementor-widget-heading\" data-id=\"1ae96b35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Il Nero d\u2019Avola Morgante \u2018Don Antonio\u2019 Riserva ha origine da uve Nero d\u2019Avola in purezza, coltivate a un\u2019altitudine di 500-550 metri sul livello del mare su terreni bianchi caratterizzati da un\u2019alta componente calcarea e dalla presenza di argilla. A seguito della raccolta, i grappoli vengono trasferiti in cantina e ammostati in serbatoi di acciaio inox, contenitori nei quali si realizza la fermentazione malolattica accompagnata da circa 20 giorni di macerazione sulle bucce, il tutto a una temperatura controllata di 26-28 \u00b0C. Anche la fermentazione malolattica si svolge in acciaio e il vino viene successivamente posto a maturare per 12 mesi in barrique nuove di rovere francese, delle tipologie Allier, Tron\u00e7ais e Never. Segue un ulteriore affinamento di un anno in bottiglia prima della definitiva uscita in commercio.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-585cf72 elementor-widget elementor-widget-heading\" data-id=\"585cf72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Il \u2018Don Antonio\u2019 Nero d\u2019Avola Riserva di Morgante \u00e8 di colore rosso rubino intenso. Al naso si percepiscono vividi aromi fruttati di amarena matura, lampone e prugna, arricchiti da profonde sensazioni di liquirizia e cioccolato. Setosa la morbidezza e imponente la struttura al palato, elementi ben bilanciati dalla piacevole freschezza e il tannino vellutato.<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-73a46b56 wd-section-stretch elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73a46b56\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27f8b576\" data-id=\"27f8b576\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-inner-section elementor-element elementor-element-42dff114 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"42dff114\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-21d5379\" data-id=\"21d5379\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-571d8fd7 elementor-widget elementor-widget-wd_infobox\" data-id=\"571d8fd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-left box-style-base color-scheme-light wd-items-top\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-text text-size-default box-icon-simple\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t1.\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title title box-title-style-default wd-fontsize-xl\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\t\u989c\u8272\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"data-elementor-setting-key=\"content\"><p>Rosso rubino intenso.<\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-64e5e3db\" data-id=\"64e5e3db\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-143cf746 elementor-widget elementor-widget-wd_infobox\" data-id=\"143cf746\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-left box-style-base color-scheme-light wd-items-top\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-text text-size-default box-icon-simple\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t2.\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title title box-title-style-default wd-fontsize-xl\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\t\u54c1\u5c1d\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"data-elementor-setting-key=\"content\"><p>Setoso, dalla struttura imponente, equilibrato, fresco e dal finale piacevolmente tannico.<\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-67b10947\" data-id=\"67b10947\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41178665 elementor-widget elementor-widget-wd_infobox\" data-id=\"41178665\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-left box-style-base color-scheme-light wd-items-top\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-text text-size-default box-icon-simple\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t3.\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title title box-title-style-default wd-fontsize-xl\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\t\u9999\u6c34\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"data-elementor-setting-key=\"content\"><p>Aromi di amarene mature, lamponi, prugne e finale speziato e di cioccolato.<\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u201cDon Antonio\u201d \u00e8 un Nero d\u2019Avola Riserva siciliano dal carattere possente e deciso, maturato per 12 mesi in nuove barriques. Il naso rivela note fruttate e speziate con accenni di cioccolato e cannella.<\/p>\n<p>Ha una struttura morbida e intensa, con una potente dose alcolica ben sostenuta da una lieve freschezza e un gradevole tannino.<\/p>","protected":false},"featured_media":284981,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":""},"product_brand":[1286],"product_cat":[427],"product_tag":[1168],"class_list":{"0":"post-32030","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-morgante","7":"product_cat-rosso","8":"product_tag-1168","9":"pa_annata-533","10":"pa_denominazione-sicilia-doc","11":"pa_formato-075-cl","12":"pa_gradazione-alcolica-13-5","13":"pa_paese-italia","14":"pa_produttore-morgante","15":"pa_regione-sicilia","16":"pa_tipologia-vini-rossi","17":"pa_vitigni-nero-davola-100","19":"first","20":"instock","21":"featured","22":"taxable","23":"shipping-taxable","24":"purchasable","25":"product-type-simple"},"ase":null,"_links":{"self":[{"href":"https:\/\/www.vinness.it\/zh\/wp-json\/wp\/v2\/product\/32030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vinness.it\/zh\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vinness.it\/zh\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vinness.it\/zh\/wp-json\/wp\/v2\/comments?post=32030"}],"version-history":[{"count":0,"href":"https:\/\/www.vinness.it\/zh\/wp-json\/wp\/v2\/product\/32030\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vinness.it\/zh\/wp-json\/wp\/v2\/media\/284981"}],"wp:attachment":[{"href":"https:\/\/www.vinness.it\/zh\/wp-json\/wp\/v2\/media?parent=32030"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.vinness.it\/zh\/wp-json\/wp\/v2\/product_brand?post=32030"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vinness.it\/zh\/wp-json\/wp\/v2\/product_cat?post=32030"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vinness.it\/zh\/wp-json\/wp\/v2\/product_tag?post=32030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}